{"id":425,"date":"2018-04-06T14:23:46","date_gmt":"2018-04-06T14:23:46","guid":{"rendered":"https:\/\/www.saiebologna.it\/?p=425"},"modified":"2018-04-06T14:23:46","modified_gmt":"2018-04-06T14:23:46","slug":"bolognafiere-affida-la-gestione-del-saie-a-senaf-del-gruppo-tecniche-nuove","status":"publish","type":"post","link":"https:\/\/www.edilio.it\/it\/comunicati\/bolognafiere-affida-la-gestione-del-saie-a-senaf-del-gruppo-tecniche-nuove\/","title":{"rendered":"BolognaFiere affida la gestione del SAIE a Senaf del Gruppo Tecniche Nuove"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-36 alignright\" src=\"\/public\/uploads\/sites\/9\/logo-senaf-e1520959957338.png\" alt=\"\" width=\"130\" height=\"53\" \/><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-35 alignright\" src=\"\/public\/uploads\/sites\/9\/tecniche-nuove.png\" alt=\"\" width=\"200\" height=\"37\" \/><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-34 alignright\" src=\"\/public\/uploads\/sites\/9\/logo-bologna-fiere.png\" alt=\"\" width=\"160\" height=\"47\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-4 alignnone alignleft\" src=\"\/public\/uploads\/sites\/9\/logo-saie.png\" alt=\"\" width=\"155\" height=\"80\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><em>Senaf, societ\u00e0 del Gruppo Tecniche Nuove, acquisisce l&#8217;organizzazione di SAIE per le prossime dieci edizioni da BolognaFiere[vc_row][vc_column][vc_empty_space][vc_column_text]<\/em><\/p>\n<hr \/>\n<p>Bologna, 09 aprile 2018 \u2013 Senaf, societ\u00e0 del Gruppo Tecniche Nuove, acquisisce l&#8217;organizzazione di SAIE per le prossime dieci edizioni da BolognaFiere che, grazie a questa nuova joint venture, rafforza il proprio posizionamento come polo fieristico di riferimento per il settore delle costruzioni.<br \/>\nIl nuovo progetto di SAIE, che partir\u00e0 sin dalla prossima edizione (Bologna, dal 17 al 20 ottobre 2018), vedr\u00e0 valorizzare sia il ruolo centrale delle eccellenze produttive del fare made in Italy e internazionale, quanto la capacit\u00e0 del settore di concretizzare in nuovi prodotti e servizi la visione del futuro di costruzioni, ristrutturazioni e infrastrutture.<br \/>\nTra le prime novit\u00e0 sono previste 4 iniziative speciali (Recupero e Protezione Sismica; Sostenibilit\u00e0, greenbuilding e integrazione impiantistica; Digital&amp;BIM Conference Lab; Infrastruttura e Territorio) e l\u2019approfondimento di 4 focus (Gestione Edificio e riqualificazione edilizia; Impianti tecnici in edilizia; Trasformazione urbana; Digitalizzazione e BIM).<\/p>\n<p>&#8220;Nel progetto di riposizionamento di SAIE, un nostro storico prodotto fieristico \u2013 commenta Antonio Bruzzone, Direttore Generale di BolognaFiere \u2013 abbiamo rivisto tutti gli aspetti passibili di miglioramenti, dal project management ai contenuti e abbiamo puntato su un nuovo assetto gestionale che prevede l\u2019affidamento a Senaf e il Gruppo Tecniche Nuove delle prossime 10 edizioni di SAIE. Siamo convinti che le competenze nel mercato fieristico e nel settore delle costruzioni e la solidit\u00e0 del Gruppo possano essere asset capaci di accelerare il riposizionamento di SAIE, che si \u00e8 posto l&#8217;obiettivo di tornare a generare un importante indotto per il territorio e per BolognaFiere.&#8221;<br \/>\n\u201cI dati previsionali dell\u2019ANCE indicano il 2018 come l\u2019anno di svolta in cui il settore torner\u00e0 a crescere del 2,4% \u2013 commenta Gianfranco Ferilli, Vice Presidente di Senaf \u2013 Avremo perci\u00f2 l\u2019importantissimo compito di valorizzare questa ripresa, con l\u2019obiettivo di portare nell\u2019arco del prossimo biennio il SAIE sul primo gradino degli appuntamenti europei professionali pi\u00f9 importanti dell\u2019industrializzazione edilizia.\u201d<\/p>\n<p>&#8220;Il nostro Gruppo \u00e8 in un\u2019importante fase di consolidamento del proprio modello di business \u2013 commenta Ivo Nardella, Amministratore Delegato del Gruppo Tecniche Nuove \u2013 Abbiamo individuato nell\u2019edilizia uno dei comparti industriali capaci di tracciare una chiara linea di demarcazione tra un\u2019Italia che guarda al passato e un paese capace di valorizzare, con infrastrutture e impianti moderni e sostenibili, il proprio territorio e le proprie citt\u00e0, con il loro patrimonio storico e architettonico. L\u2019idea di sostenere il progetto di rilancio del SAIE, accanto a BolognaFiere e importanti componenti associative nazionali e territoriali, oltre che motivo di orgoglio, ci permetter\u00e0 di mettere a disposizione il nostro sistema di competenze fatto di riviste, eventi, libri, formazione e soluzioni digitali.&#8221;<\/p>\n<hr \/>\n<p><strong>I numeri di Saie 2016<\/strong><\/p>\n<p>52.453 Visitatori<br \/>\n1718 Visitatori Esteri<br \/>\n+400 espositori<br \/>\n13 iniziative speciali<br \/>\n222 Convegni e Seminari<br \/>\n51.335 mq area occupata<\/p>\n<hr \/>\n<p><strong>BolognaFiere<\/strong> \u00e8 tra i principali organizzatori fieristici internazionali e uno dei quartieri espositivi pi\u00f9 avanzati al mondo.<br \/>\nIl Gruppo BolognaFiere gestisce tre quartieri fieristici (Bologna, Modena e Ferrara) con oltre 75 manifestazioni leader in Italia e all\u2019estero; \u00e8 attivo con numerose societ\u00e0 che realizzano una vasta proposta espositiva e che forniscono alle aziende tutti i servizi specialistici e di promozione per partecipare con successo ad ogni manifestazione fieristica.<\/p>\n<p><strong>Senaf<\/strong>, da oltre 35 anni, \u00e8 impegnata nell\u2019organizzare alcune tra le pi\u00f9 efficaci manifestazioni dedicate ad un pubblico altamente qualificato, sempre attenta a generare conoscenza mettendo in connessione tutti gli attori presenti in fiera. Negli ultimi anni, assecondando il mercato, Senaf ha riprogettato le proprie manifestazioni, partendo dalle necessit\u00e0 del visitatore. Ha introdotto nuovi strumenti di promozione e comunicazione al fine di massimizzare l\u2019investimento degli espositori. Servizi di matching per gli espositori, cataloghi per dispositivi mobili, profilazione dei visitatori, newsletter, personalizzazione degli strumenti elettronici di promozione, sono solo alcuni dei servizi a disposizione di chi partecipa ad una fiera Senaf.<\/p>\n<p>L\u2019attenzione al cambiamento dei mercati, alle nuove tecnologie ed alle nuove forme di comunicazione a sostegno della fiera, affiancati a progetti ben strutturati, sono alcuni dei punti di forza delle fiere Senaf.<\/p>\n<p>Il<strong> Gruppo Tecniche Nuove<\/strong> con circa 260 dipendenti e 56 milioni di euro di fatturato \u00e8 leader nell&#8217;editoria specializzata per le attivit\u00e0 produttive e professionali e presente sia nel settore dei corsi di aggiornamento professionale sia nell\u2019organizzazione di fiere e congressi.<\/p>\n<p>Nata negli anni \u201860 come realt\u00e0 editoriale specializzata nella meccanica, ha saputo evolvere il proprio business inserendosi in un numero sempre maggiore di settori industriali. Il business del Gruppo Tecniche Nuove si sviluppa su diversi asset, che garantiscono ai professionisti un\u2019offerta di comunicazione completa e globale sui settori di industria meccanica e automazione, impiantistica e costruzioni, architettura e interni, alimentare e food processing, agricoltura, della medicina, salute e benessere, industria chimica e farmaceutica, dell\u2019ho.re.ca., retail, informatica e ICT. I principali canali sono:<br \/>\n&#8211; Riviste: Tecniche Nuove \u00e8 leader nell&#8217;informazione specializzata nelle attivit\u00e0 produttive e professionali, grazie a un&#8217;offerta di oltre 140 riviste sia cartacee sia digitali.<br \/>\n&#8211; Libri: il Gruppo \u00e8 leader nell&#8217;editoria di settore, con 1.050 libri a catalogo e oltre 5.000 titoli pubblicati.<br \/>\n&#8211; Corsi di formazione: ampia e articolata \u00e8 l&#8217;offerta formativa del gruppo con 120 corsi di formazione di cui 70 ECM (Educazione Continua in Medicina) e altri di aggiornamento online per tecnici e professionisti. Tecniche Nuove \u00e8 provider accreditato dalla Commissione Nazionale ECM per la formazione delle professioni sanitarie.<br \/>\n&#8211; Siti web: il Gruppo \u00e8 presente sul web con un ampio network di siti e portali dedicati al mondo delle attivit\u00e0 sia produttive sia professionali.<br \/>\n&#8211; Fiere: da oltre trent&#8217;anni, attraverso Senaf, societ\u00e0 del Gruppo, Tecniche Nuove d\u00e0 vita alle pi\u00f9 efficaci manifestazioni (23 nel 2018) legate alla meccanica specializzata, all&#8217;impiantistica, alla logistica, alle tecnologie della moda, alla salute, alla sanit\u00e0 al noleggio e all&#8217;edilizia.<\/p>\n[\/vc_column_text][\/vc_column]\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Senaf, societ\u00e0 del Gruppo Tecniche Nuove, acquisisce l&#8217;organizzazione di SAIE per le prossime dieci edizioni da BolognaFiere[vc_row][vc_column][vc_empty_space][vc_column_text] Bologna, 09 aprile 2018 \u2013 Senaf, societ\u00e0 del Gruppo Tecniche Nuove, acquisisce l&#8217;organizzazione di SAIE per le prossime dieci edizioni da BolognaFiere che, grazie a questa nuova joint venture, rafforza il proprio posizionamento [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/posts\/425"}],"collection":[{"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/comments?post=425"}],"version-history":[{"count":0,"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/posts\/425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/media\/430"}],"wp:attachment":[{"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/media?parent=425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/categories?post=425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edilio.it\/it\/wp-json\/wp\/v2\/tags?post=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}